{"id":8318,"date":"2021-10-05T08:41:13","date_gmt":"2021-10-05T08:41:13","guid":{"rendered":"https:\/\/otbb.org\/?page_id=8318"},"modified":"2025-08-28T10:27:50","modified_gmt":"2025-08-28T10:27:50","slug":"tourisme","status":"publish","type":"page","link":"https:\/\/otbb.org\/en\/tourisme\/","title":{"rendered":"Tourism"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8318\" class=\"elementor elementor-8318\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90515c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90515c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b71559e\" data-id=\"b71559e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8452bb1 elementor-widget elementor-widget-shortcode\" data-id=\"8452bb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"custom-title-pages-container tourisme-container\"><h2 id=\"tourisme\" class=\"custom-title-pages-green custom-title-pages\">TOURISM<\/h2><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a0ad79 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a0ad79\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abcdbce\" data-id=\"abcdbce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f53475 elementor-widget elementor-widget-html\" data-id=\"3f53475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--\n    Voici un exemple de config pour un slider,\n    tu peux la changer en regardant la doc de swiper\n    et mes commentaires pour l'adapter a tes besoins.\n    Je t'ai aussi comment\u00e9 le CSS personnnalis\u00e9 afin\n    que tu puisses modifier \/ adpater \u00e9galement.\n-->\n\n\n\n<div class=\"section-with-swiper-slider\">\n    <div id=\"section-tourisme2-container\">\n        <div id=\"title-swiper-container-fix-width\">\n            <h2 class=\"section-swiper-title\">Individual tours:<\/h2>\n        <\/div>\n        \n        \n        <!-- Desktop -->\n        <p class=\"paragraph-section-swiper paragraph-section-swiper-desktop\">\n            You won\u2019t find better guides than our enthusiastic and passionate speakers!\nThe Tourist Office enlists a team of guides who are specialists educated in history, art and architecture.\nWe organise a lot of guided tours throughout the year, so be sure to take a look at our bi-yearly program!\n        <\/p>\n        \n        <!-- Desktop -->\n        <a class=\"btn-section-swiper btn-section-swiper-desktop\" href=\"https:\/\/otbb.org\/en\/visites-guidees-individuelles\/\">\n                <span>LEARN MORE<\/span>\n                <svg width=\"25\" height=\"25\" class=\"svg-aria\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\"><path data-name=\"Trac\u00e9 1088\" class=\"svg-aria\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1089\" class=\"svg-aria\"  d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1090\" class=\"svg-aria\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n                <\/svg>\n            <\/a>\n        \n        <!-- Mobile -->\n        <a class=\"btn-section-swiper btn-section-swiper-mobile2\" href=\"https:\/\/otbb.org\/en\/visites-guidees-individuelles\/\">\n            <svg width=\"25\" height=\"25\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\">\n                <path data-name=\"Trac\u00e9 1088\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1089\" d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1090\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n            <\/svg>\n        <\/a>\n    <\/div>\n    \n    <div class=\"section-swiper-tourisme2\">\n        <div\n            style=\"                width: 100%;                height: 100%;                overflow-y: hidden;            \"\n        >\n            <!--\n                Change l'ID du container pour chacun\n                des sliders que tu dois faire,\n                c'est gr\u00e2ce \u00e0 lui que tu peux les\n                appeler en JS donc mets des noms uniques\n                (je te conseille cette forme: \n                swiper-NomDeTaSection-container)\n            -->\n            <div id=\"swiper-tourisme2-container\">\n                <div class=\"swiper-wrapper\">\n                    <!--\n                        Change les images des slides ici,\n                        ajouter des liens si besoin\n                        etc (le contenu quoi)\n                    -->\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/01-Musee_Paul_Belmondo_Photo_Henri_Delage-2011-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/HDV-Exterieur-AdB-020-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 533px; --smush-placeholder-aspect-ratio: 533\/533;\"><\/div>\n     \n                     <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/MA30-Small-5-1.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 520px; --smush-placeholder-aspect-ratio: 520\/520;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/Boulogne-Nord-scaled.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1714px; --smush-placeholder-aspect-ratio: 1714\/2560;\"><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        \n        <!--\n            Ajoute les classes de la navigation pour chacun\n            des sliders que tu dois faire, c'est gr\u00e2ce \u00e0 eux que\n            tu peux appeler la navigation en JS donc mets des\n            noms uniques (je te conseille cette forme: \n            swiper-NomDeTaSection-button-prev pour le bouton 'pr\u00e9c\u00e9dent'\n            et swiper-NomDeTaSection-button-next pour le bouton 'suivant')\n        -->\n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourisme2-button-prev\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n        \n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourisme2-button-next\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n    <\/div>\n    \n    <!-- Mobile -->\n    <p class=\"paragraph-section-swiper paragraph-section-swiper-mobile\">\n        You won't find a better guide than our engaging and passionate speakers!\n\nThe Tourist Office boasts a team of qualified speakers specializing in history, art, and architecture.\n\nWe organize numerous guided tours throughout the year. Take a look at our semester program!\n    <\/p>\n<\/div>\n\n<script>\nnew Swiper(\n\/* \n    Change l'ID du container a appeler pour\n    chaque slider, il correspond a celui du\n    container de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n    '#swiper-tourisme2-container',\n\/* \n    Les param\u00e8tres si dessous sont indiqu\u00e9 dans\n    la doc, pose des questions au pole dev\n    seuelement si tu ne trouves pas la r\u00e9ponse\n    dans celle-ci\n    Lien vers les param\u00e8tres:\n    https:\/\/swiperjs.com\/swiper-api#parameters\n*\/\n    {\n        autoplay: true,\n        speed: 500,\n        spaceBetween: 10,\n        slidesPerView: 2,\n        loop: true,\n        loopedSlides: 4,\n        \n        navigation: {\n\/* \n    Change les classes de la pagination a appeler pour\n    chaque slider, ils correspondent a celui de la navigation\n    de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n            nextEl: '.swiper-tourisme2-button-next',\n            prevEl: '.swiper-tourisme2-button-prev',\n        },\n    }\n);\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1baa989 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"1baa989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/otbb.org\/en\/ile-seguin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8262d4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8262d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f976919\" data-id=\"f976919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1be9589 elementor-widget elementor-widget-html\" data-id=\"1be9589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--\n    Voici un exemple de config pour un slider,\n    tu peux la changer en regardant la doc de swiper\n    et mes commentaires pour l'adapter a tes besoins.\n    Je t'ai aussi comment\u00e9 le CSS personnnalis\u00e9 afin\n    que tu puisses modifier \/ adpater \u00e9galement.\n-->\n\n\n\n<div class=\"section-with-swiper-slider\">\n    <div id=\"section-tourismeGroupe-container\">\n        <div id=\"title-swiper-container-fix-width-2\">\n            <h2 id=\"title-groupe\" class=\"section-swiper-title\">Group tours:<\/h2>\n        <\/div>\n        \n        \n        <!-- Desktop -->\n        <p class=\"paragraph-section-swiper paragraph-section-swiper-desktop\">\n            To make the most of a city as culturally and architecturally rich as Boulogne-Billancourt, you\u2019ll need a guide to show you around. There are a million things to know about the area, so listening to your guide\u2019s stories and anecdotes will make for exciting tours and help you really get a feel for the city, which is proud to be among the \u201cTowns of Art and History\".\nBoulogne-Billancourt\u2019s Tourist Office offers tailor-made services (visits and\/or hotel\/restaurant reservations) with attractive group pricing.\n        <\/p>\n        \n        <!-- Desktop -->\n        <a class=\"btn-section-swiper btn-section-swiper-desktop\" href=\"https:\/\/otbb.org\/en\/visites-guidees-de-groupes\/\">\n                <span>LEARN MORE<\/span>\n                <svg width=\"25\" height=\"25\" class=\"svg-aria\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\"><path data-name=\"Trac\u00e9 1088\" class=\"svg-aria\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1089\" class=\"svg-aria\" d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1090\" class=\"svg-aria\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n                <\/svg>\n            <\/a>\n        \n        <!-- Mobile -->\n        <a class=\"btn-section-swiper btn-section-swiper-mobile\" href=\"https:\/\/otbb.org\/en\/visites-guidees-de-groupes\/\">\n            <svg width=\"25\" height=\"25\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\">\n                <path data-name=\"Trac\u00e9 1088\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1089\" d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1090\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n            <\/svg>\n        <\/a>\n    <\/div>\n    \n    <div class=\"section-swiper-tourismeGroupe\">\n        <div\n            style=\"                width: 100%;                height: 100%;                overflow-y: hidden;            \"\n        >\n            <!--\n                Change l'ID du container pour chacun\n                des sliders que tu dois faire,\n                c'est gr\u00e2ce \u00e0 lui que tu peux les\n                appeler en JS donc mets des noms uniques\n                (je te conseille cette forme: \n                swiper-NomDeTaSection-container)\n            -->\n            <div id=\"swiper-tourismeGroupe-container\">\n                <div class=\"swiper-wrapper\">\n                    <!--\n                        Change les images des slides ici,\n                        ajouter des liens si besoin\n                        etc (le contenu quoi)\n                    -->\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/VILLA-1-scaled.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2219px; --smush-placeholder-aspect-ratio: 2219\/2560;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/\u00a9X_Muyard-muse\u0301e-jardin-A-small.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/1500;\"><\/div>\n     \n                     <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/05-et-14-Parcours-des-Annees-30.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 614px; --smush-placeholder-aspect-ratio: 614\/614;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/11\/Bibliothe\u0300que-Marmottan-Ext-scaled.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1707px; --smush-placeholder-aspect-ratio: 1707\/2560;\"><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        \n        <!--\n            Ajoute les classes de la navigation pour chacun\n            des sliders que tu dois faire, c'est gr\u00e2ce \u00e0 eux que\n            tu peux appeler la navigation en JS donc mets des\n            noms uniques (je te conseille cette forme: \n            swiper-NomDeTaSection-button-prev pour le bouton 'pr\u00e9c\u00e9dent'\n            et swiper-NomDeTaSection-button-next pour le bouton 'suivant')\n        -->\n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourismeGroupe-button-prev\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n        \n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourismeGroupe-button-next\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n    <\/div>\n    \n    <!-- Mobile -->\n    <p class=\"paragraph-section-swiper paragraph-section-swiper-mobile\">\n        To make the most of a city as culturally and architecturally rich as Boulogne-Billancourt, you\u2019ll need a guide to show you around. There are a million things to know about the area, so listening to your guide\u2019s stories and anecdotes will make for exciting tours and help you really get a feel for the city, which is proud to be among the \u201cTowns of Art and History\".\nBoulogne-Billancourt\u2019s Tourist Office offers tailor-made services (visits and\/or hotel\/restaurant reservations) with attractive group pricing.\n    <\/p>\n<\/div>\n\n<script>\nnew Swiper(\n\/* \n    Change l'ID du container a appeler pour\n    chaque slider, il correspond a celui du\n    container de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n    '#swiper-tourismeGroupe-container',\n\/* \n    Les param\u00e8tres si dessous sont indiqu\u00e9 dans\n    la doc, pose des questions au pole dev\n    seuelement si tu ne trouves pas la r\u00e9ponse\n    dans celle-ci\n    Lien vers les param\u00e8tres:\n    https:\/\/swiperjs.com\/swiper-api#parameters\n*\/\n    {\n        autoplay: true,\n        speed: 500,\n        spaceBetween: 10,\n        slidesPerView: 2,\n        loop: true,\n        loopedSlides: 4,\n        \n        navigation: {\n\/* \n    Change les classes de la pagination a appeler pour\n    chaque slider, ils correspondent a celui de la navigation\n    de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n            nextEl: '.swiper-tourismeGroupe-button-next',\n            prevEl: '.swiper-tourismeGroupe-button-prev',\n        },\n    }\n);\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa241f6 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"aa241f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/otbb.org\/en\/visites-guidees-de-groupes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72a7463 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72a7463\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-faa29e2\" data-id=\"faa29e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1625633 elementor-widget elementor-widget-html\" data-id=\"1625633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--\n    Voici un exemple de config pour un slider,\n    tu peux la changer en regardant la doc de swiper\n    et mes commentaires pour l'adapter a tes besoins.\n    Je t'ai aussi comment\u00e9 le CSS personnnalis\u00e9 afin\n    que tu puisses modifier \/ adpater \u00e9galement.\n-->\n\n\n\n<div class=\"section-with-swiper-slider\">\n    <div id=\"section-tourismeMusees-container\">\n        <h2 class=\"section-swiper-title title-musee\">Museums<\/h2>\n        \n        <!-- Desktop -->\n        <p class=\"paragraph-section-swiper paragraph-section-swiper-desktop\">\n            Boulogne-Billancourt boasts three unique municipal museums: The 30s Museum is revered around the world, and the Paul-Landowski and Paul-Belmondo museums honour the two artists with beautifully staged, modern exhibitions. \n        <\/p>\n        <p class=\"paragraph-section-swiper paragraph-section-swiper-desktop\" style = \"margin-top: -%;\">\n            The city\u2019s Albert Kahn Museum and its gardens are a refreshing change of scene for the many visitors it welcomes across the year.\nFinally, the Pavillon des Projets is the gem of the eco-district it\u2019s located in and offers educational workshops for children and adults alike.\n        <\/p>\n        \n        <!-- Desktop -->\n        <a class=\"btn-section-swiper btn-section-swiper-desktop\" href=\"https:\/\/otbb.org\/en\/musees\/\">\n                <span>LEARN MORE<\/span>\n                <svg width=\"25\" height=\"25\" class=\"svg-aria\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\"><path data-name=\"Trac\u00e9 1088\" class=\"svg-aria\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1089\" class=\"svg-aria\" d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/><path data-name=\"Trac\u00e9 1090\" class=\"svg-aria\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n                <\/svg>\n            <\/a>\n        \n        <!-- Mobile -->\n        <a class=\"btn-section-swiper btn-section-swiper-mobile\" href=\"#\">\n            <svg width=\"25\" height=\"25\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 19.907 19.041\">\n                <path data-name=\"Trac\u00e9 1088\" d=\"M13.2 10.172H.649a.65.65 0 0 1 0-1.3H13.2a.65.65 0 0 1 0 1.3Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1089\" d=\"M9.737 13.632a.65.65 0 0 1-.459-1.109l3-3-3-3a.65.65 0 1 1 .918-.918l3.462 3.462a.649.649 0 0 1 0 .918l-3.462 3.462a.644.644 0 0 1-.459.185Zm0 0\" fill=\"#fff\"\/>\n                <path data-name=\"Trac\u00e9 1090\" d=\"M10.386 19.041a9.471 9.471 0 0 1-8.861-6.038.649.649 0 1 1 1.208-.474 8.222 8.222 0 1 0 0-6.017.649.649 0 1 1-1.208-.474 9.521 9.521 0 1 1 8.861 13Zm0 0\" fill=\"#fff\"\/>\n            <\/svg>\n        <\/a>\n    <\/div>\n    \n    <div class=\"section-swiper-tourismeMusees\">\n        <div\n            style=\"                width: 100%;                height: 100%;                overflow-y: hidden;            \"\n        >\n            <!--\n                Change l'ID du container pour chacun\n                des sliders que tu dois faire,\n                c'est gr\u00e2ce \u00e0 lui que tu peux les\n                appeler en JS donc mets des noms uniques\n                (je te conseille cette forme: \n                swiper-NomDeTaSection-container)\n            -->\n            <div id=\"swiper-tourismeMusees-container\">\n                <div class=\"swiper-wrapper\">\n                    <!--\n                        Change les images des slides ici,\n                        ajouter des liens si besoin\n                        etc (le contenu quoi)\n                    -->\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/1-Musee_Paul_Landowski_photo_Philippe_Fuzeau_Septembre-2017-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/15-Musee_Paul_Belmondo_Photo_Philippe-Fuzeau-Juin-2013-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\"><\/div>\n     \n                     <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/Ambiance-4eme_1_photo_Philippe_Fuzeau_2020-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\"><\/div>\n                    <div class=\"swiper-slide\">\n                    <img decoding=\"async\" class=\"fit-picture lazyload\"\n     data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/MDAK-jardin-japonais-contemporain-HD-\u00a9-CD92-Stephanie-Gutierrez-Ortega-Carre.jpg\"\n     alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\"><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        \n        <!--\n            Ajoute les classes de la navigation pour chacun\n            des sliders que tu dois faire, c'est gr\u00e2ce \u00e0 eux que\n            tu peux appeler la navigation en JS donc mets des\n            noms uniques (je te conseille cette forme: \n            swiper-NomDeTaSection-button-prev pour le bouton 'pr\u00e9c\u00e9dent'\n            et swiper-NomDeTaSection-button-next pour le bouton 'suivant')\n        -->\n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourismeMusees-button-prev\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n        \n        <div\n            style=\"background-image: none\"\n            class=\"swiper-tourismeMusees-button-next\"\n        >\n            <svg data-name=\"Scroll droit\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 46 46\">\n            \t<g data-name=\"Groupe 16227\">\n            \t\t<g data-name=\"Groupe 16219\">\n            \t\t\t<path data-name=\"Ligne 9\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m26.395 19.001 3.96 4.102\"\/>\n            \t\t\t<path data-name=\"Ligne 10\" fill=\"none\" stroke=\"#fff\" stroke-linecap=\"round\" stroke-width=\"2\" d=\"m30.015 23.433-3.76 3.631\"\/>\n            \t\t\t<path data-name=\"Trac\u00e9 17996\" d=\"M29.637 24.046H15.72a.977.977 0 0 1 0-1.885h13.917a.977.977 0 0 1 0 1.885Zm0 0\" fill=\"#fff\"\/>\n            \t\t<\/g>\n            \t<\/g>\n            <\/svg>\n        <\/div>\n    <\/div>\n    \n    <!-- Mobile -->\n    <p class=\"paragraph-section-swiper paragraph-section-swiper-mobile\">\n        The Albert Kahn Departmental Museum and its gardens, located within the town limits, welcome numerous visitors, who are always captivated by the change of scenery this place offers.\n\nFinally, the Projects Pavilion showcases the eco-district in which it is situated and offers educational workshops for children and adults.\n    <\/p>\n<\/div>\n\n<script>\nnew Swiper(\n\/* \n    Change l'ID du container a appeler pour\n    chaque slider, il correspond a celui du\n    container de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n    '#swiper-tourismeMusees-container',\n\/* \n    Les param\u00e8tres si dessous sont indiqu\u00e9 dans\n    la doc, pose des questions au pole dev\n    seuelement si tu ne trouves pas la r\u00e9ponse\n    dans celle-ci\n    Lien vers les param\u00e8tres:\n    https:\/\/swiperjs.com\/swiper-api#parameters\n*\/\n    {\n        autoplay: true,\n        speed: 500,\n        spaceBetween: 10,\n        slidesPerView: 2,\n        loop: true,\n        loopedSlides: 4,\n        \n        navigation: {\n\/* \n    Change les classes de la pagination a appeler pour\n    chaque slider, ils correspondent a celui de la navigation\n    de ton slider (comme pr\u00e9cis\u00e9 plus haut)\n*\/\n            nextEl: '.swiper-tourismeMusees-button-next',\n            prevEl: '.swiper-tourismeMusees-button-prev',\n        },\n    }\n);\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99e61d1 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"99e61d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/otbb.org\/en\/musees\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6756da6 elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6756da6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0e2e69\" data-id=\"d0e2e69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84aa226 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84aa226\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f79ccf1\" data-id=\"f79ccf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4dea3 elementor-widget elementor-widget-shortcode\" data-id=\"7d4dea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"custom-title-pages-container default-container\"><h2 id=\"default\" class=\"custom-title-pages-green custom-title-pages\">l'\u00eele seguin<\/h2><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f766416 elementor-widget elementor-widget-image\" data-id=\"f766416\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"456\" src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL.jpg\" class=\"attachment-large size-large wp-image-22863\" alt=\"\" srcset=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL.jpg 800w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-300x182.jpg 300w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-768x467.jpg 768w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-18x12.jpg 18w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-600x365.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\" style=\"width:100%;height:60.75%;max-width:800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb23a42 elementor-widget elementor-widget-text-editor\" data-id=\"cb23a42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Since the closure of the Renault \u201cfactory island\u201d in 1992, \u00cele Seguin has been transformed and now hosts many remarkable facilities at the heart of the Seine riverbank ecosystem and a dynamic urban center.\u00a0<\/p><p>Fancy watching some live music in the middle of an architectural masterpiece? Head over to the Seine Musicale, created by Jean de Gastines and Shigeru Ban (Pritzker Prize 2014) and opened in 2017.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85749a2 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"85749a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/otbb.org\/en\/ile-seguin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16410ce elementor-section-stretched elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16410ce\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b7bafbf\" data-id=\"b7bafbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2ec83b ile-seguin elementor-widget elementor-widget-shortcode\" data-id=\"d2ec83b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"custom-title-pages-container default-container\"><h2 id=\"default\" class=\"custom-title-pages-green custom-title-pages\">l'\u00eele seguin<\/h2><\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-938fa48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"938fa48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d237802\" data-id=\"d237802\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fd3fc3\" data-id=\"5fd3fc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ab63d0 elementor-widget elementor-widget-text-editor\" data-id=\"0ab63d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Since the closure of the Renault \u201cIsland-factory\u201d in 1992, Ile Seguin has been transformed into a dynamic urban hub and has welcomed many remarkable facilities into its riverside community.&nbsp;<\/span><\/p><p><span style=\"font-weight: 400;\"><br><\/span><\/p><p><span style=\"font-weight: 400;\">Fancy watching some live music in the middle of an architectural masterpiece? Head over to the Seine Musicale, created by Jean de Gastines and Shigeru Ban (Pritzker Prize 2014) and opened in 2017. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f9332 elementor-widget elementor-widget-button\" data-id=\"c6f9332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/otbb.org\/en\/ile-seguin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bcf91ee\" data-id=\"bcf91ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f13e271 elementor-widget elementor-widget-image\" data-id=\"f13e271\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"456\" data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-768x467.jpg\" class=\"attachment-medium_large size-medium_large wp-image-22863 lazyload\" alt=\"\" data-srcset=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-768x467.jpg 768w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-300x182.jpg 300w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-18x12.jpg 18w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL-600x365.jpg 600w, https:\/\/otbb.org\/wp-content\/uploads\/2022\/08\/La-Seine-Musicale-et-pont-de-sevres-\u00a9-Nicolas-Grosmond-SMALL.jpg 800w\" data-sizes=\"(max-width: 750px) 100vw, 750px\" style=\"--smush-placeholder-width: 750px; --smush-placeholder-aspect-ratio: 750\/456;width:100%;height:60.75%;max-width:800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fc2643 elementor-section-stretched elementor-hidden-phone elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fc2643\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d549202\" data-id=\"d549202\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1315ef9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1315ef9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45e2530\" data-id=\"45e2530\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f22edb4 elementor-widget elementor-widget-image\" data-id=\"f22edb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"121\" height=\"123\" data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png\" class=\"attachment-large size-large wp-image-9531 lazyload\" alt=\"rond rose\" data-srcset=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png 121w, https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004-12x12.png 12w\" data-sizes=\"(max-width: 121px) 100vw, 121px\" style=\"--smush-placeholder-width: 121px; --smush-placeholder-aspect-ratio: 121\/123;width:100%;height:101.65%;max-width:121px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d8b71ed\" data-id=\"d8b71ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff6d09a Section-titreh2 elementor-widget elementor-widget-text-editor\" data-id=\"ff6d09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Ile Seguin (Seguin Island)<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1039d86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1039d86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5cc827\" data-id=\"d5cc827\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-409ce50\" data-id=\"409ce50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c15395 elementor-widget elementor-widget-text-editor\" data-id=\"3c15395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Depuis la fermeture de \u00ab\u00a0l&rsquo;\u00eele-usine\u00a0\u00bb Renault en 1992, l\u2019\u00cele Seguin se m\u00e9tamorphose et accueille de nombreux \u00e9quipements remarquables au c\u0153ur de l\u2019\u00e9cosyst\u00e8me des rives de la Seine et d\u2019un p\u00f4le urbain dynamique. La Seine musicale inaugur\u00e9e en 2017 fait vivre toutes les musiques au c\u0153ur d\u2019un \u00e9crin architectural r\u00e9alis\u00e9 par Jean de Gastines et Shigeru Ban (Prix Pritzker 2014). <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3084889 elementor-widget elementor-widget-button\" data-id=\"3084889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8011bb1\" data-id=\"8011bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fd4807 elementor-widget elementor-widget-image\" data-id=\"8fd4807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/09\/Image_2-11.png\" title=\"\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Visites guid\u00e9es individuelles Vous ne serez pas mieux guid\u00e9s que par nos conf\u00e9renciers passionnants et passionn\u00e9s ! L\u2019Office de Tourisme s\u2019entoure d\u2019une \u00e9quipe de conf\u00e9renciers dipl\u00f4m\u00e9s et sp\u00e9cialistes d\u2019histoire, d\u2019art et d\u2019architecture. Nous organisons de nombreuses visites guid\u00e9es tout au long de l\u2019ann\u00e9e. Jetez donc un \u0153il \u00e0 notre programmation semestrielle ! EN SAVOIR PLUS&hellip; <a class=\"more-link\" href=\"https:\/\/otbb.org\/en\/tourisme\/\">Continue reading <span class=\"screen-reader-text\">Tourism<\/span><\/a><\/p>","protected":false},"author":171,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-8318","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt<\/title>\n<meta name=\"description\" content=\"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/otbb.org\/en\/tourisme\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt\" \/>\n<meta property=\"og:description\" content=\"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/otbb.org\/en\/tourisme\/\" \/>\n<meta property=\"og:site_name\" content=\"OTBB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OTBB92\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T10:27:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OTBB92\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/\",\"url\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/\",\"name\":\"Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Trace-18004.png\",\"datePublished\":\"2021-10-05T08:41:13+00:00\",\"dateModified\":\"2025-08-28T10:27:50+00:00\",\"description\":\"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/otbb.org\\\/tourisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Trace-18004.png\",\"contentUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Trace-18004.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/otbb.org\\\/tourisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/otbb.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tourisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#website\",\"url\":\"https:\\\/\\\/otbb.org\\\/\",\"name\":\"OTBB\",\"description\":\"Bienvenue sur le site de l\u2019office du tourisme de Boulogne Billancourt\",\"publisher\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/otbb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#organization\",\"name\":\"OTBB\",\"url\":\"https:\\\/\\\/otbb.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo_OTBB_horiz_QUADRI.webp\",\"contentUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo_OTBB_horiz_QUADRI.webp\",\"width\":1035,\"height\":345,\"caption\":\"OTBB\"},\"image\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OTBB92\\\/\",\"https:\\\/\\\/x.com\\\/OTBB92\",\"https:\\\/\\\/www.instagram.com\\\/otbb92\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt","description":"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/otbb.org\/en\/tourisme\/","og_locale":"en_GB","og_type":"article","og_title":"Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt","og_description":"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.","og_url":"https:\/\/otbb.org\/en\/tourisme\/","og_site_name":"OTBB","article_publisher":"https:\/\/www.facebook.com\/OTBB92\/","article_modified_time":"2025-08-28T10:27:50+00:00","og_image":[{"url":"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@OTBB92","twitter_misc":{"Estimated reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/otbb.org\/tourisme\/","url":"https:\/\/otbb.org\/tourisme\/","name":"Visites guid\u00e9es et mus\u00e9es. Tourisme \u00e0 Boulogne-Billancourt","isPartOf":{"@id":"https:\/\/otbb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/otbb.org\/tourisme\/#primaryimage"},"image":{"@id":"https:\/\/otbb.org\/tourisme\/#primaryimage"},"thumbnailUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png","datePublished":"2021-10-05T08:41:13+00:00","dateModified":"2025-08-28T10:27:50+00:00","description":"Tourisme \u00e0 Boulogne-Billancourt : D\u00e9couvrez nos mus\u00e9es, jardin Albert Kahn et visites guid\u00e9es th\u00e9matiques dans les quartiers de la ville.","breadcrumb":{"@id":"https:\/\/otbb.org\/tourisme\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/otbb.org\/tourisme\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/otbb.org\/tourisme\/#primaryimage","url":"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png","contentUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2021\/10\/Trace-18004.png"},{"@type":"BreadcrumbList","@id":"https:\/\/otbb.org\/tourisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/otbb.org\/"},{"@type":"ListItem","position":2,"name":"Tourisme"}]},{"@type":"WebSite","@id":"https:\/\/otbb.org\/#website","url":"https:\/\/otbb.org\/","name":"OTBB","description":"Bienvenue sur le site de l\u2019office du tourisme de Boulogne Billancourt","publisher":{"@id":"https:\/\/otbb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/otbb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/otbb.org\/#organization","name":"OTBB","url":"https:\/\/otbb.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/otbb.org\/#\/schema\/logo\/image\/","url":"https:\/\/otbb.org\/wp-content\/uploads\/2024\/04\/cropped-logo_OTBB_horiz_QUADRI.webp","contentUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2024\/04\/cropped-logo_OTBB_horiz_QUADRI.webp","width":1035,"height":345,"caption":"OTBB"},"image":{"@id":"https:\/\/otbb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OTBB92\/","https:\/\/x.com\/OTBB92","https:\/\/www.instagram.com\/otbb92\/"]}]}},"_links":{"self":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/pages\/8318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/comments?post=8318"}],"version-history":[{"count":141,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/pages\/8318\/revisions"}],"predecessor-version":[{"id":40337,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/pages\/8318\/revisions\/40337"}],"wp:attachment":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/media?parent=8318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}