{"id":44791,"date":"2026-05-13T08:28:43","date_gmt":"2026-05-13T08:28:43","guid":{"rendered":"https:\/\/otbb.org\/?post_type=product&#038;p=44791"},"modified":"2026-05-13T08:32:57","modified_gmt":"2026-05-13T08:32:57","slug":"parcours-des-annees-30-en-langue-des-signes","status":"publish","type":"product","link":"https:\/\/otbb.org\/en\/product\/parcours-des-annees-30-en-langue-des-signes\/","title":{"rendered":"Parcours des ann\u00e9es 30 en Langue des Signes"},"content":{"rendered":"<p>L\u2019entre-deux-guerres fut \u00e0 Boulogne-Billancourt un temps d\u2019intense cr\u00e9ation architecturale. Les plus grands architectes du XX\u00e8me si\u00e8cle b\u00e2tirent des \u00e9difices qui inspirent le monde entier. Leur ma\u00eetre-mot : la modernit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>Le temps d\u2019une visite culturelle, votre guide captivera les grands comme les petits en leur faisant d\u00e9couvrir tous les secrets et les histoires de ces magnifiques fa\u00e7ades et constructions embl\u00e9matiques du quartier des Princes.<\/p>\n<p>&nbsp;<\/p>\n<p>Une visite accessible en langue des signes fran\u00e7ais.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Sur les traces des ma\u00eetres.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>14h30 &#8211; 16h00<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>R\u00e9servation obligatoire \u00e0 l\u2019Office de Tourisme :<\/strong> 01 41 41 54 54 ou otbb.org<\/p>\n<p>&nbsp;<\/p>\n<p>Dans la limite de 16 places disponibles.<\/p>","protected":false},"featured_media":25374,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[69],"product_tag":[],"class_list":{"0":"post-44791","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agenda-events","7":"entry","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parcours des ann\u00e9es 30 en Langue des Signes - OTBB<\/title>\n<meta name=\"description\" content=\"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/otbb.org\/en\/product\/parcours-des-annees-30-en-langue-des-signes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parcours des ann\u00e9es 30 en Langue des Signes - OTBB\" \/>\n<meta property=\"og:description\" content=\"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/otbb.org\/en\/product\/parcours-des-annees-30-en-langue-des-signes\/\" \/>\n<meta property=\"og:site_name\" content=\"OTBB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OTBB92\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:32:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/otbb.org\/wp-content\/uploads\/2022\/12\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OTBB92\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/\",\"url\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/\",\"name\":\"Parcours des ann\u00e9es 30 en Langue des Signes - OTBB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg\",\"datePublished\":\"2026-05-13T08:28:43+00:00\",\"dateModified\":\"2026-05-13T08:32:57+00:00\",\"description\":\"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg\",\"contentUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/otbb.org\\\/produit\\\/parcours-des-annees-30-en-langue-des-signes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/otbb.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/otbb.org\\\/boutique-et-livres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Parcours des ann\u00e9es 30 en Langue des Signes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#website\",\"url\":\"https:\\\/\\\/otbb.org\\\/\",\"name\":\"OTBB\",\"description\":\"Bienvenue sur le site de l\u2019office du tourisme de Boulogne Billancourt\",\"publisher\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/otbb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#organization\",\"name\":\"OTBB\",\"url\":\"https:\\\/\\\/otbb.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/otbb.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo_OTBB_horiz_QUADRI.webp\",\"contentUrl\":\"https:\\\/\\\/otbb.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo_OTBB_horiz_QUADRI.webp\",\"width\":1035,\"height\":345,\"caption\":\"OTBB\"},\"image\":{\"@id\":\"https:\\\/\\\/otbb.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OTBB92\\\/\",\"https:\\\/\\\/x.com\\\/OTBB92\",\"https:\\\/\\\/www.instagram.com\\\/otbb92\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parcours des ann\u00e9es 30 en Langue des Signes - OTBB","description":"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/otbb.org\/en\/product\/parcours-des-annees-30-en-langue-des-signes\/","og_locale":"en_GB","og_type":"article","og_title":"Parcours des ann\u00e9es 30 en Langue des Signes - OTBB","og_description":"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.","og_url":"https:\/\/otbb.org\/en\/product\/parcours-des-annees-30-en-langue-des-signes\/","og_site_name":"OTBB","article_publisher":"https:\/\/www.facebook.com\/OTBB92\/","article_modified_time":"2026-05-13T08:32:57+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/otbb.org\/wp-content\/uploads\/2022\/12\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OTBB92","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/","url":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/","name":"Parcours des ann\u00e9es 30 en Langue des Signes - OTBB","isPartOf":{"@id":"https:\/\/otbb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/#primaryimage"},"image":{"@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/#primaryimage"},"thumbnailUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2022\/12\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg","datePublished":"2026-05-13T08:28:43+00:00","dateModified":"2026-05-13T08:32:57+00:00","description":"Parcours des ann\u00e9es 30 en LSF : Sur les traces des ma\u00eetres. Rendez-vous le samedi 20 juin 2026 de 10h \u00e0 12h au 1 rue du Belv\u00e9d\u00e8re.","breadcrumb":{"@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/#primaryimage","url":"https:\/\/otbb.org\/wp-content\/uploads\/2022\/12\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg","contentUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2022\/12\/10.-Parcours-annee-30_7-rue-des-Arts_Photo-\u00a9Philippe-Fuzeau.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/otbb.org\/produit\/parcours-des-annees-30-en-langue-des-signes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/otbb.org\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/otbb.org\/boutique-et-livres\/"},{"@type":"ListItem","position":3,"name":"Parcours des ann\u00e9es 30 en Langue des Signes"}]},{"@type":"WebSite","@id":"https:\/\/otbb.org\/#website","url":"https:\/\/otbb.org\/","name":"OTBB","description":"Bienvenue sur le site de l\u2019office du tourisme de Boulogne Billancourt","publisher":{"@id":"https:\/\/otbb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/otbb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/otbb.org\/#organization","name":"OTBB","url":"https:\/\/otbb.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/otbb.org\/#\/schema\/logo\/image\/","url":"https:\/\/otbb.org\/wp-content\/uploads\/2024\/04\/cropped-logo_OTBB_horiz_QUADRI.webp","contentUrl":"https:\/\/otbb.org\/wp-content\/uploads\/2024\/04\/cropped-logo_OTBB_horiz_QUADRI.webp","width":1035,"height":345,"caption":"OTBB"},"image":{"@id":"https:\/\/otbb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OTBB92\/","https:\/\/x.com\/OTBB92","https:\/\/www.instagram.com\/otbb92\/"]}]}},"_links":{"self":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product\/44791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/comments?post=44791"}],"version-history":[{"count":1,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product\/44791\/revisions"}],"predecessor-version":[{"id":44800,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product\/44791\/revisions\/44800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/media\/25374"}],"wp:attachment":[{"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/media?parent=44791"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product_brand?post=44791"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product_cat?post=44791"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/otbb.org\/en\/wp-json\/wp\/v2\/product_tag?post=44791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}